{"id":125408,"date":"2026-04-20T19:41:03","date_gmt":"2026-04-20T17:41:03","guid":{"rendered":"https:\/\/www.toysgames.be\/la-boutique\/non%20class\u00e9\/star-wars-casque-clone-phase-1\/"},"modified":"2026-04-22T16:49:41","modified_gmt":"2026-04-22T14:49:41","slug":"star-wars-casque-clone-phase-1","status":"publish","type":"product","link":"https:\/\/www.toysgames.be\/nl\/la-boutique\/popcultuur\/decoratie\/star-wars-casque-clone-phase-1\/","title":{"rendered":"Star Wars &#8211; Casque Clone Phase 1"},"content":{"rendered":"<span class=\"et_bloom_bottom_trigger\"><\/span>","protected":false},"excerpt":{"rendered":"","protected":false},"featured_media":0,"template":"","meta":{"_acf_changed":false,"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":"","om_disable_all_campaigns":false,"_monsterinsights_skip_tracking":false},"product_brand":[],"product_cat":[264],"product_tag":[],"class_list":["post-125408","product","type-product","status-publish","product_cat-decoration","first","instock","sold-individually","taxable","shipping-taxable","purchasable","product-type-simple"],"acf":[],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO 5.0.1.1 - aioseo.com -->\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"google-site-verification\" content=\"ymRM0Ssx9qQLBVff4g2YS-d_PA6sfWZKKMxPQKhR1lI\" \/>\n\t<link rel=\"canonical\" href=\"https:\/\/www.toysgames.be\/nl\/la-boutique\/popcultuur\/decoratie\/star-wars-casque-clone-phase-1\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 5.0.1.1\" \/>\n\t\t<meta property=\"og:locale\" content=\"nl_NL\" \/>\n\t\t<meta property=\"og:site_name\" content=\"Toys Games - La seconde main de qualit\u00e9, \u00e0 port\u00e9e de tous\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"Star Wars \u2013 Casque Clone Phase 1 - Toys Games\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/www.toysgames.be\/nl\/la-boutique\/popcultuur\/decoratie\/star-wars-casque-clone-phase-1\/\" \/>\n\t\t<meta property=\"fb:admins\" content=\"61565407109066\" \/>\n\t\t<meta property=\"og:image\" content=\"https:\/\/www.toysgames.be\/wp-content\/uploads\/2025\/09\/logo-site1.png\" \/>\n\t\t<meta property=\"og:image:secure_url\" content=\"https:\/\/www.toysgames.be\/wp-content\/uploads\/2025\/09\/logo-site1.png\" \/>\n\t\t<meta property=\"og:image:width\" content=\"512\" \/>\n\t\t<meta property=\"og:image:height\" content=\"512\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2026-04-20T17:41:03+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2026-04-22T14:49:41+00:00\" \/>\n\t\t<meta property=\"article:publisher\" content=\"https:\/\/facebook.com\/ToysGamesBelgique\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n\t\t<meta name=\"twitter:title\" content=\"Star Wars \u2013 Casque Clone Phase 1 - Toys Games\" \/>\n\t\t<meta name=\"twitter:image\" content=\"https:\/\/www.toysgames.be\/wp-content\/uploads\/2025\/09\/logo-site1.png\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.toysgames.be\\\/nl\\\/la-boutique\\\/popcultuur\\\/decoratie\\\/star-wars-casque-clone-phase-1\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.toysgames.be\\\/nl\\\/#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.toysgames.be\\\/nl\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.toysgames.be\\\/nl\\\/de-winkel\\\/#listItem\",\"name\":\"De winkel\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.toysgames.be\\\/nl\\\/de-winkel\\\/#listItem\",\"position\":2,\"name\":\"De winkel\",\"item\":\"https:\\\/\\\/www.toysgames.be\\\/nl\\\/de-winkel\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.toysgames.be\\\/nl\\\/categorie-produit\\\/pop-culture\\\/#listItem\",\"name\":\"Pop-Culture\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.toysgames.be\\\/nl\\\/#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.toysgames.be\\\/nl\\\/categorie-produit\\\/pop-culture\\\/#listItem\",\"position\":3,\"name\":\"Pop-Culture\",\"item\":\"https:\\\/\\\/www.toysgames.be\\\/nl\\\/categorie-produit\\\/pop-culture\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.toysgames.be\\\/nl\\\/categorie-produit\\\/pop-culture\\\/decoration\\\/#listItem\",\"name\":\"D\\u00e9coration\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.toysgames.be\\\/nl\\\/de-winkel\\\/#listItem\",\"name\":\"De winkel\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.toysgames.be\\\/nl\\\/categorie-produit\\\/pop-culture\\\/decoration\\\/#listItem\",\"position\":4,\"name\":\"D\\u00e9coration\",\"item\":\"https:\\\/\\\/www.toysgames.be\\\/nl\\\/categorie-produit\\\/pop-culture\\\/decoration\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.toysgames.be\\\/nl\\\/la-boutique\\\/popcultuur\\\/decoratie\\\/star-wars-casque-clone-phase-1\\\/#listItem\",\"name\":\"Star Wars &#8211; Casque Clone Phase 1\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.toysgames.be\\\/nl\\\/categorie-produit\\\/pop-culture\\\/#listItem\",\"name\":\"Pop-Culture\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.toysgames.be\\\/nl\\\/la-boutique\\\/popcultuur\\\/decoratie\\\/star-wars-casque-clone-phase-1\\\/#listItem\",\"position\":5,\"name\":\"Star Wars &#8211; Casque Clone Phase 1\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.toysgames.be\\\/nl\\\/categorie-produit\\\/pop-culture\\\/decoration\\\/#listItem\",\"name\":\"D\\u00e9coration\"}}]},{\"@type\":\"ItemPage\",\"@id\":\"https:\\\/\\\/www.toysgames.be\\\/nl\\\/la-boutique\\\/popcultuur\\\/decoratie\\\/star-wars-casque-clone-phase-1\\\/#itempage\",\"url\":\"https:\\\/\\\/www.toysgames.be\\\/nl\\\/la-boutique\\\/popcultuur\\\/decoratie\\\/star-wars-casque-clone-phase-1\\\/\",\"name\":\"Star Wars \\u2013 Casque Clone Phase 1 - Toys Games\",\"inLanguage\":\"nl-NL\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.toysgames.be\\\/nl\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.toysgames.be\\\/nl\\\/la-boutique\\\/popcultuur\\\/decoratie\\\/star-wars-casque-clone-phase-1\\\/#breadcrumblist\"},\"datePublished\":\"2026-04-20T19:41:03+02:00\",\"dateModified\":\"2026-04-22T16:49:41+02:00\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.toysgames.be\\\/nl\\\/#organization\",\"name\":\"Toys Games\",\"description\":\"La seconde main de qualit\\u00e9, \\u00e0 port\\u00e9e de tous\",\"url\":\"https:\\\/\\\/www.toysgames.be\\\/nl\\\/\",\"email\":\"info@toysgames.be\",\"telephone\":\"+3269767953\",\"foundingDate\":\"2024-12-07\",\"numberOfEmployees\":{\"@type\":\"QuantitativeValue\",\"value\":1},\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/www.toysgames.be\\\/wp-content\\\/uploads\\\/2025\\\/09\\\/logo-site1.png\",\"@id\":\"https:\\\/\\\/www.toysgames.be\\\/nl\\\/la-boutique\\\/popcultuur\\\/decoratie\\\/star-wars-casque-clone-phase-1\\\/#organizationLogo\",\"width\":512,\"height\":512},\"image\":{\"@id\":\"https:\\\/\\\/www.toysgames.be\\\/nl\\\/la-boutique\\\/popcultuur\\\/decoratie\\\/star-wars-casque-clone-phase-1\\\/#organizationLogo\"},\"sameAs\":[\"https:\\\/\\\/facebook.com\\\/ToysGamesBelgique\",\"https:\\\/\\\/www.instagram.com\\\/toysgamesbelgique\\\/\"]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.toysgames.be\\\/nl\\\/#website\",\"url\":\"https:\\\/\\\/www.toysgames.be\\\/nl\\\/\",\"name\":\"Toys Games\",\"alternateName\":\"Toys Games\",\"description\":\"La seconde main de qualit\\u00e9, \\u00e0 port\\u00e9e de tous\",\"inLanguage\":\"nl-NL\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.toysgames.be\\\/nl\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"Star Wars \u2013 Casque Clone Phase 1 - Toys Games","description":"","canonical_url":"https:\/\/www.toysgames.be\/nl\/la-boutique\/popcultuur\/decoratie\/star-wars-casque-clone-phase-1\/","robots":"max-image-preview:large","keywords":"","webmasterTools":{"google-site-verification":"ymRM0Ssx9qQLBVff4g2YS-d_PA6sfWZKKMxPQKhR1lI","miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BreadcrumbList","@id":"https:\/\/www.toysgames.be\/nl\/la-boutique\/popcultuur\/decoratie\/star-wars-casque-clone-phase-1\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/www.toysgames.be\/nl\/#listItem","position":1,"name":"Home","item":"https:\/\/www.toysgames.be\/nl\/","nextItem":{"@type":"ListItem","@id":"https:\/\/www.toysgames.be\/nl\/de-winkel\/#listItem","name":"De winkel"}},{"@type":"ListItem","@id":"https:\/\/www.toysgames.be\/nl\/de-winkel\/#listItem","position":2,"name":"De winkel","item":"https:\/\/www.toysgames.be\/nl\/de-winkel\/","nextItem":{"@type":"ListItem","@id":"https:\/\/www.toysgames.be\/nl\/categorie-produit\/pop-culture\/#listItem","name":"Pop-Culture"},"previousItem":{"@type":"ListItem","@id":"https:\/\/www.toysgames.be\/nl\/#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/www.toysgames.be\/nl\/categorie-produit\/pop-culture\/#listItem","position":3,"name":"Pop-Culture","item":"https:\/\/www.toysgames.be\/nl\/categorie-produit\/pop-culture\/","nextItem":{"@type":"ListItem","@id":"https:\/\/www.toysgames.be\/nl\/categorie-produit\/pop-culture\/decoration\/#listItem","name":"D\u00e9coration"},"previousItem":{"@type":"ListItem","@id":"https:\/\/www.toysgames.be\/nl\/de-winkel\/#listItem","name":"De winkel"}},{"@type":"ListItem","@id":"https:\/\/www.toysgames.be\/nl\/categorie-produit\/pop-culture\/decoration\/#listItem","position":4,"name":"D\u00e9coration","item":"https:\/\/www.toysgames.be\/nl\/categorie-produit\/pop-culture\/decoration\/","nextItem":{"@type":"ListItem","@id":"https:\/\/www.toysgames.be\/nl\/la-boutique\/popcultuur\/decoratie\/star-wars-casque-clone-phase-1\/#listItem","name":"Star Wars &#8211; Casque Clone Phase 1"},"previousItem":{"@type":"ListItem","@id":"https:\/\/www.toysgames.be\/nl\/categorie-produit\/pop-culture\/#listItem","name":"Pop-Culture"}},{"@type":"ListItem","@id":"https:\/\/www.toysgames.be\/nl\/la-boutique\/popcultuur\/decoratie\/star-wars-casque-clone-phase-1\/#listItem","position":5,"name":"Star Wars &#8211; Casque Clone Phase 1","previousItem":{"@type":"ListItem","@id":"https:\/\/www.toysgames.be\/nl\/categorie-produit\/pop-culture\/decoration\/#listItem","name":"D\u00e9coration"}}]},{"@type":"ItemPage","@id":"https:\/\/www.toysgames.be\/nl\/la-boutique\/popcultuur\/decoratie\/star-wars-casque-clone-phase-1\/#itempage","url":"https:\/\/www.toysgames.be\/nl\/la-boutique\/popcultuur\/decoratie\/star-wars-casque-clone-phase-1\/","name":"Star Wars \u2013 Casque Clone Phase 1 - Toys Games","inLanguage":"nl-NL","isPartOf":{"@id":"https:\/\/www.toysgames.be\/nl\/#website"},"breadcrumb":{"@id":"https:\/\/www.toysgames.be\/nl\/la-boutique\/popcultuur\/decoratie\/star-wars-casque-clone-phase-1\/#breadcrumblist"},"datePublished":"2026-04-20T19:41:03+02:00","dateModified":"2026-04-22T16:49:41+02:00"},{"@type":"Organization","@id":"https:\/\/www.toysgames.be\/nl\/#organization","name":"Toys Games","description":"La seconde main de qualit\u00e9, \u00e0 port\u00e9e de tous","url":"https:\/\/www.toysgames.be\/nl\/","email":"info@toysgames.be","telephone":"+3269767953","foundingDate":"2024-12-07","numberOfEmployees":{"@type":"QuantitativeValue","value":1},"logo":{"@type":"ImageObject","url":"https:\/\/www.toysgames.be\/wp-content\/uploads\/2025\/09\/logo-site1.png","@id":"https:\/\/www.toysgames.be\/nl\/la-boutique\/popcultuur\/decoratie\/star-wars-casque-clone-phase-1\/#organizationLogo","width":512,"height":512},"image":{"@id":"https:\/\/www.toysgames.be\/nl\/la-boutique\/popcultuur\/decoratie\/star-wars-casque-clone-phase-1\/#organizationLogo"},"sameAs":["https:\/\/facebook.com\/ToysGamesBelgique","https:\/\/www.instagram.com\/toysgamesbelgique\/"]},{"@type":"WebSite","@id":"https:\/\/www.toysgames.be\/nl\/#website","url":"https:\/\/www.toysgames.be\/nl\/","name":"Toys Games","alternateName":"Toys Games","description":"La seconde main de qualit\u00e9, \u00e0 port\u00e9e de tous","inLanguage":"nl-NL","publisher":{"@id":"https:\/\/www.toysgames.be\/nl\/#organization"}}]},"og:locale":"nl_NL","og:site_name":"Toys Games - La seconde main de qualit\u00e9, \u00e0 port\u00e9e de tous","og:type":"article","og:title":"Star Wars \u2013 Casque Clone Phase 1 - Toys Games","og:url":"https:\/\/www.toysgames.be\/nl\/la-boutique\/popcultuur\/decoratie\/star-wars-casque-clone-phase-1\/","fb:admins":"61565407109066","og:image":"https:\/\/www.toysgames.be\/wp-content\/uploads\/2025\/09\/logo-site1.png","og:image:secure_url":"https:\/\/www.toysgames.be\/wp-content\/uploads\/2025\/09\/logo-site1.png","og:image:width":512,"og:image:height":512,"article:published_time":"2026-04-20T17:41:03+00:00","article:modified_time":"2026-04-22T14:49:41+00:00","article:publisher":"https:\/\/facebook.com\/ToysGamesBelgique","twitter:card":"summary_large_image","twitter:title":"Star Wars \u2013 Casque Clone Phase 1 - Toys Games","twitter:image":"https:\/\/www.toysgames.be\/wp-content\/uploads\/2025\/09\/logo-site1.png"},"aioseo_meta_data":{"post_id":"125408","title":"#post_title #separator_sa #site_title","description":"#post_excerpt","keywords":null,"keyphrases":{"focus":[],"additional":[]},"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":null,"og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"","isEnabled":true},"graphs":[]},"schema_type":"default","schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":null,"robots_max_videopreview":null,"robots_max_imagepreview":"large","priority":null,"frequency":null,"local_seo":null,"breadcrumb_settings":null,"limit_modified_date":false,"ai":null,"created":"2026-04-20 19:03:29","updated":"2026-08-12 13:28:04","seo_analyzer_scan_date":null,"focus_keyword":null,"additional_keywords":null,"truseo_locale":null},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/www.toysgames.be\/nl\/\" title=\"Home\">Home<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">\u00bb<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/www.toysgames.be\/nl\/de-winkel\/\" title=\"De winkel\">De winkel<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">\u00bb<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/www.toysgames.be\/nl\/categorie-produit\/pop-culture\/\" title=\"Pop-Culture\">Pop-Culture<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">\u00bb<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/www.toysgames.be\/nl\/categorie-produit\/pop-culture\/decoration\/\" title=\"D\u00e9coration\">D\u00e9coration<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">\u00bb<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\tStar Wars \u2013 Casque Clone Phase 1\n\t\t<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/www.toysgames.be\/nl\/"},{"label":"De winkel","link":"https:\/\/www.toysgames.be\/nl\/de-winkel\/"},{"label":"Pop-Culture","link":"https:\/\/www.toysgames.be\/nl\/categorie-produit\/pop-culture\/"},{"label":"D\u00e9coration","link":"https:\/\/www.toysgames.be\/nl\/categorie-produit\/pop-culture\/decoration\/"},{"label":"Star Wars &#8211; Casque Clone Phase 1","link":"https:\/\/www.toysgames.be\/nl\/la-boutique\/popcultuur\/decoratie\/star-wars-casque-clone-phase-1\/"}],"_links":{"self":[{"href":"https:\/\/www.toysgames.be\/nl\/wp-json\/wp\/v2\/product\/125408","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.toysgames.be\/nl\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/www.toysgames.be\/nl\/wp-json\/wp\/v2\/types\/product"}],"wp:attachment":[{"href":"https:\/\/www.toysgames.be\/nl\/wp-json\/wp\/v2\/media?parent=125408"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/www.toysgames.be\/nl\/wp-json\/wp\/v2\/product_brand?post=125408"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/www.toysgames.be\/nl\/wp-json\/wp\/v2\/product_cat?post=125408"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/www.toysgames.be\/nl\/wp-json\/wp\/v2\/product_tag?post=125408"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}